{"id":1029,"date":"2024-09-11T10:00:55","date_gmt":"2024-09-11T13:00:55","guid":{"rendered":"https:\/\/renavefacil.net\/blog\/?p=1029"},"modified":"2024-09-10T14:45:06","modified_gmt":"2024-09-10T17:45:06","slug":"serpro-o-que-e","status":"publish","type":"post","link":"https:\/\/renavefacil.net\/blog\/2024\/09\/11\/serpro-o-que-e\/","title":{"rendered":"SERPRO: o que \u00e9?"},"content":{"rendered":"<p>SERPRO: voc\u00ea conhece ou j\u00e1 ouviu falar? Essa empresa desempenha um papel crucial na moderniza\u00e7\u00e3o da gest\u00e3o p\u00fablica brasileira!<\/p>\n<p>A principal fun\u00e7\u00e3o desta organiza\u00e7\u00e3o \u00e9 desenvolver, gerenciar e administrar sistemas tecnol\u00f3gicos que auxiliam o governo federal em suas atividades. Por isso, \u00e9 considerada a maior empresa p\u00fablica de tecnologia da informa\u00e7\u00e3o do Brasil.<\/p>\n<p>Em uma analogia, este \u00e9 um grande computador que <b>funciona como o c\u00e9rebro da tecnologia governamental<\/b>, especialmente porque armazena informa\u00e7\u00f5es cr\u00edticas com seguran\u00e7a.<\/p>\n<p>Para entender o que \u00e9 o SERPRO continue a leitura.<\/p>\n<h2>O que \u00e9 o SERPRO?<\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" title=\"O que \u00e9 o SERPRO?\" src=\"https:\/\/renavefacil.net\/blog\/wp-content\/uploads\/2024\/09\/o-que-e-serpro.jpg\" alt=\"O que \u00e9 o SERPRO?\" width=\"768\" height=\"512\" \/><br \/>\nO SERPRO, ou Servi\u00e7o Federal de Processamento de Dados, \u00e9 a maior empresa p\u00fablica (estatal) de <b>presta\u00e7\u00e3o de servi\u00e7os de Tecnologia da Informa\u00e7\u00e3o do Brasil<\/b>.<\/p>\n<p>Ele foi criado em 1964, pela <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/LEIS\/L4516.htm\" target=\"_blank\" rel=\"noopener\">Lei n\u00ba 4.516<\/a>, revogada pela <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/LEIS\/L5615.htm#art16\" target=\"_blank\" rel=\"noopener\">Lei n\u00ba 5.615<\/a>, de 13 de outubro de 1970, com o objetivo de modernizar e oferecer agilidade a setores estrat\u00e9gicos da Administra\u00e7\u00e3o P\u00fablica brasileira.<\/p>\n<p>Inicialmente, essa institui\u00e7\u00e3o tinha como fun\u00e7\u00e3o modernizar e agilizar os sistemas de dados estrat\u00e9gicos da administra\u00e7\u00e3o p\u00fablica da Uni\u00e3o.<\/p>\n<p>Mas, ao longo do tempo, o \u00f3rg\u00e3o foi crescendo e passou a desenvolver solu\u00e7\u00f5es de transpar\u00eancia para a receita e gastos p\u00fablicos.<\/p>\n<p>Hoje, dentro do sistema h\u00e1 tecnologias usadas por servi\u00e7os de diversos \u00f3rg\u00e3os p\u00fablicos federais, estaduais e municipais.<\/p>\n<p>O grande objetivo do \u00f3rg\u00e3o \u00e9 <b>conectar governo e sociedade por meio de solu\u00e7\u00f5es digitais<\/b>. O <a href=\"https:\/\/www.serpro.gov.br\/menu\/quem-somos\" target=\"_blank\" rel=\"noopener\">SERPRO<\/a> \u00e9 l\u00edder no mercado de TI para o setor p\u00fablico: \u201c<i>nosso compromisso \u00e9 com a seguran\u00e7a, qualidade e confiabilidade<\/i>\u201d.<\/p>\n<p>Al\u00e9m disso, a empresa possui:<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Presen\u00e7a nacional;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Robusta infraestrutura tecnol\u00f3gica;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Ampla experi\u00eancia com os grandes sistemas da Administra\u00e7\u00e3o P\u00fablica Federal.<\/li>\n<\/ul>\n<p>Com isso, o SERPRO consegue ampliar sua atua\u00e7\u00e3o no mercado, oferecendo servi\u00e7os especializados para os setores privado e p\u00fablico, baseados em informa\u00e7\u00f5es de governo com oferta de produtos diversificados.<\/p>\n<h2>Principais fun\u00e7\u00f5es do SERPRO<\/h2>\n<p>O SERPRO fornece produtos e servi\u00e7os para as institui\u00e7\u00f5es p\u00fablicas brasileiras, al\u00e9m de algumas institui\u00e7\u00f5es privadas. Entre os servi\u00e7os mais relevantes est\u00e3o:<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Cadastro de Pessoa F\u00edsica (CPF);<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Cadastro Nacional de Pessoa Jur\u00eddica (CNPJ);<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Carteira Nacional de Habilita\u00e7\u00e3o Digital (CNH);<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Certificado digital de pessoas f\u00edsicas e jur\u00eddicas;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Datavalid: solu\u00e7\u00e3o de an\u00e1lise de informa\u00e7\u00f5es de cadastro, identidade e biometria facial;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Sistema de Notifica\u00e7\u00e3o Eletr\u00f4nica (SNE);<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">APIs do CPF, CNPJ e Nota Fiscal Eletr\u00f4nica (NFe);<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Registro Nacional de Ve\u00edculos Automotores (RENAVAM).<\/li>\n<\/ul>\n<p>O SERPRO tem tamb\u00e9m outras responsabilidades:<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Organizar o Congresso Internacional Software Livre e Governo Eletr\u00f4nico (<a href=\"https:\/\/funag.gov.br\/biblioteca-nova\/produto\/1-301-congresso_internacional_software_livre_e_governo_eletronico_vi_consegi_\" target=\"_blank\" rel=\"noopener\">CONSEGI<\/a>);<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Administrar cursos, como o de capacita\u00e7\u00e3o em E-Gov (Governo Eletr\u00f4nico).<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Unificar dados de registro de identidades locais em um banco de dados nacional, o DNI (Documento Nacional de Identidade\/RG).<\/li>\n<\/ul>\n<h2>Como ter acesso ao SERPRO?<\/h2>\n<p><img decoding=\"async\" src=\"https:\/\/renavefacil.net\/blog\/wp-content\/uploads\/2024\/09\/como-ter-acesso-ao-serpro.jpg\" alt=\"Como ter acesso ao SERPRO?\" width=\"768\" height=\"512\" \/><br \/>\nDe forma geral, o acesso ao SERPRO \u00e9 <b>restrito a usu\u00e1rios autorizados e com credenciais espec\u00edficas<\/b>, cujo procedimento de registo ocorre na fase de contrata\u00e7\u00e3o.<\/p>\n<p>Tal fato \u00e9 explicado pela natureza confidencial das informa\u00e7\u00f5es processadas pela empresa, que desenvolve e mant\u00e9m sistemas com dados sigilosos.<\/p>\n<p>Mas, em alguns casos, h\u00e1 portais espec\u00edficos para que o cidad\u00e3o comum possa acessar informa\u00e7\u00f5es ou realizar servi\u00e7os. No entanto, a gama de servi\u00e7os dispon\u00edveis para o p\u00fablico \u00e9 limitada.<\/p>\n<p>Para a contrata\u00e7\u00e3o do servi\u00e7o, basta acessar o site da empresa, clicar na aba \u201c<a href=\"https:\/\/loja.serpro.gov.br\/?utm_source=portal&amp;utm_content=20210302--botao-menu\" target=\"_blank\" rel=\"noopener\">loja<\/a>\u201d e seguir os passos para contratar o servi\u00e7o desejado.<\/p>\n<h2>Qual \u00e9 a rela\u00e7\u00e3o entre o SERPRO e o RENAVE?<\/h2>\n<p>Uma das principais atribui\u00e7\u00f5es do SERPRO \u00e9 o desenvolvimento e a manuten\u00e7\u00e3o de sistemas de informa\u00e7\u00e3o para o governo federal, caso do RENAVE.<\/p>\n<p>O\u00a0<a href=\"https:\/\/renavefacil.net\/blog\/2023\/09\/28\/renave-o-que-e-e-como-funciona-o-sistema\/\">RENAVE<\/a> (Registro Nacional de Ve\u00edculos Automotores) \u00e9 um banco de dados com informa\u00e7\u00f5es sobre todos os ve\u00edculos automotores registrados no Brasil.<\/p>\n<p>Tamb\u00e9m destinado \u00e0\u00a0<a href=\"https:\/\/renavefacil.net\/blog\/2023\/02\/15\/transformacao-digital-no-setor-automotivo\/\">transforma\u00e7\u00e3o digital<\/a> do setor automotivo, ele \u00e9 utilizado para diversas finalidades, como:<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Transfer\u00eancia de propriedade de ve\u00edculos<\/b>: ao realizar a compra de um ve\u00edculo, \u00e9 necess\u00e1rio fazer a transfer\u00eancia de propriedade no RENAVE;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Consulta de d\u00e9bitos<\/b>: O RENAVE permite consultar d\u00e9bitos de IPVA, multas e outros encargos relacionados ao ve\u00edculo;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Emiss\u00e3o de documentos<\/b>: emiss\u00e3o do Certificado de Registro e Licenciamento do Ve\u00edculo (CRLV-e) e o Licenciamento Anual.<\/li>\n<\/ul>\n<p>Para explicar a rela\u00e7\u00e3o entre ambos, podemos adaptar a analogia feita na introdu\u00e7\u00e3o deste artigo. Ou seja, o SERPRO \u00e9 o <b>c\u00e9rebro por tr\u00e1s do RENAVE<\/b>. A associa\u00e7\u00e3o ocorre de tr\u00eas formas:<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Desenvolvimento e manuten\u00e7\u00e3o<\/b>: o SERPRO desenvolve e mant\u00e9m toda a tecnologia que alimenta e gerencia o RENAVE;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Infraestrutura<\/b>: a institui\u00e7\u00e3o federal fornece a infraestrutura tecnol\u00f3gica necess\u00e1ria para o funcionamento do RENAVE, como servidores, redes e sistemas de seguran\u00e7a;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Inova\u00e7\u00e3o<\/b>: o SERPRO busca solu\u00e7\u00f5es tecnol\u00f3gicas que tornam os processos mais seguros e eficientes.<\/li>\n<\/ul>\n<p>Gra\u00e7as a essa parceria, o RENAVE se tornou um sistema fundamental para a gest\u00e3o do parque veicular brasileiro.<\/p>\n<p><a href=\"https:\/\/conteudo.renavefacil.net\/infografico-tudo-que-voce-precisa-saber-sobre-o-renave\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" title=\"Tudo sobre o Renave. Acesse e confira o infogr\u00e1fico!\" src=\"https:\/\/renavefacil.net\/blog\/wp-content\/uploads\/2023\/10\/tudo-sobre-o-renave-infografico.png\" alt=\"Tudo sobre o Renave. Acesse e confira o infogr\u00e1fico!\" width=\"1600\" height=\"480\" \/><\/a><\/p>\n<h2>Como fazer o credenciamento do SERPRO para utilizar o RENAVE?<\/h2>\n<p>O credenciamento no SERPRO \u00e9 o primeiro passo para a integra\u00e7\u00e3o e habilita\u00e7\u00e3o do RENAVE.<\/p>\n<p>Para esse procedimento, \u00e9 preciso solicitar o credenciamento por meio do portal da <a href=\"https:\/\/credencia.estaleiro.serpro.gov.br\/credencia-web\/#\/login\" target=\"_blank\" rel=\"noopener\">Credencia<\/a>, ligado ao sistema do governo.<\/p>\n<p>Para isso, v\u00e1rios documentos s\u00e3o necess\u00e1rios, como:<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Certificado digital do tipo A1;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Termo de Compromisso de Manuten\u00e7\u00e3o de Sigilo (TCMS) devidamente preenchido e assinado;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Firma reconhecida;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">C\u00f3pia da CNH;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">RG, CPF e CNPJ da empresa.<\/li>\n<\/ul>\n<p>Para saber mais, basta conferir nosso artigo:\u00a0<a href=\"https:\/\/renavefacil.net\/blog\/2022\/07\/14\/como-fazer-o-credenciamento-no-serpro\/\">Como fazer o credenciamento no SERPRO?<\/a><\/p>\n<h3><\/h3>\n<h3>Esse processo pode ser terceirizado?<\/h3>\n<p>O credenciamento \u00e9 um processo relativamente f\u00e1cil, mas ele pode, sim, ser terceirizado.<br \/>\nEssa op\u00e7\u00e3o \u00e9 ideal para concession\u00e1rias que desejam um suporte extra de especialistas durante todo o processo de habilita\u00e7\u00e3o ao RENAVE e\u00a0<a href=\"https:\/\/renavefacil.net\/blog\/2022\/05\/24\/saiba-como-otimizar-a-transferencia-veicular-na-concessionaria\/\">transfer\u00eancia veicular<\/a>.<\/p>\n<p>A <a href=\"https:\/\/renavefacil.net\/blog\/2021\/06\/25\/renave-facil-o-futuro-e-hoje\/\">Renave F\u00e1cil<\/a>, por exemplo, disponibiliza um time apto e competente para realizar este processo. Basta dar o aval e a documenta\u00e7\u00e3o necess\u00e1ria para os especialistas do suporte realizarem esse processo para voc\u00ea!<\/p>\n<p>A \u00fanica exig\u00eancia \u00e9 que o estabelecimento, durante a contrata\u00e7\u00e3o da integra\u00e7\u00e3o ao RENAVE, adquira um pacote de cr\u00e9ditos. Eles ser\u00e3o utilizados posteriormente durante as entradas de ve\u00edculos no sistema.<\/p>\n<p>Al\u00e9m de uma interface intuitiva e de f\u00e1cil uso, a ferramenta \u00e9 segura e pr\u00e1tica, com o passo a passo dos processos muito bem explicados.<\/p>\n<p>Ficou curioso sobre essa solu\u00e7\u00e3o facilitadora? Ent\u00e3o transfira com mais agilidade seus ve\u00edculos novos e seminovos no estoque Renave!<\/p>\n<p><a href=\"https:\/\/conteudo.renavefacil.net\/cadastro-na-plataforma\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" title=\"Digitaliza\u00e7\u00e3o do setor automotivo: saiba como aplicar no dia a dia!\" src=\"https:\/\/renavefacil.net\/blog\/wp-content\/uploads\/2024\/02\/digitalizacao-no-setor-automotivo.jpg\" alt=\"Digitaliza\u00e7\u00e3o do setor automotivo: saiba como aplicar no dia a dia!\" width=\"780\" height=\"300\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SERPRO: voc\u00ea conhece ou j\u00e1 ouviu falar? Essa empresa desempenha um papel crucial na moderniza\u00e7\u00e3o da gest\u00e3o p\u00fablica brasileira! A principal fun\u00e7\u00e3o desta organiza\u00e7\u00e3o \u00e9 desenvolver, gerenciar e administrar sistemas tecnol\u00f3gicos que auxiliam o governo federal em suas atividades. Por isso, \u00e9 considerada a maior empresa p\u00fablica de tecnologia da informa\u00e7\u00e3o do Brasil. Em uma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1030,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"SERPRO: o que \u00e9?","_seopress_titles_desc":"Inova\u00e7\u00e3o e tecnologia de TI a servi\u00e7o do governo federal, o SERPRO desenvolve solu\u00e7\u00f5es digitais que impulsionam a transforma\u00e7\u00e3o digital do pa\u00eds. Saiba mais!","_seopress_robots_index":"","footnotes":""},"categories":[5,7],"tags":[73,69,37,74,55,75],"class_list":["post-1029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informativo","category-setor-automotivo","tag-governo","tag-o-que-e-serpro","tag-serpro","tag-sistema","tag-tecnologia","tag-veiculos"],"jetpack_featured_media_url":"https:\/\/renavefacil.net\/blog\/wp-content\/uploads\/2024\/09\/serpro.jpg","_links":{"self":[{"href":"https:\/\/renavefacil.net\/blog\/wp-json\/wp\/v2\/posts\/1029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renavefacil.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/renavefacil.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/renavefacil.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/renavefacil.net\/blog\/wp-json\/wp\/v2\/comments?post=1029"}],"version-history":[{"count":0,"href":"https:\/\/renavefacil.net\/blog\/wp-json\/wp\/v2\/posts\/1029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renavefacil.net\/blog\/wp-json\/wp\/v2\/media\/1030"}],"wp:attachment":[{"href":"https:\/\/renavefacil.net\/blog\/wp-json\/wp\/v2\/media?parent=1029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/renavefacil.net\/blog\/wp-json\/wp\/v2\/categories?post=1029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/renavefacil.net\/blog\/wp-json\/wp\/v2\/tags?post=1029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}